{"id":2402,"date":"2016-07-14T12:31:53","date_gmt":"2016-07-14T12:31:53","guid":{"rendered":"https:\/\/www.eem.ca\/fr\/2016\/07\/14\/job-opportunity-consultant-social-impact-assessment\/"},"modified":"2016-11-30T22:51:49","modified_gmt":"2016-11-30T21:51:49","slug":"consultant-en-matiere-d-evaluation-de-l-impact-social","status":"publish","type":"post","link":"https:\/\/www.eem.ca\/fr\/2016\/07\/14\/consultant-en-matiere-d-evaluation-de-l-impact-social\/","title":{"rendered":"Offre d&#8217;emploi &#8211; Consultant en \u00e9valuation de l&rsquo;impact social"},"content":{"rendered":"<p><strong>Description de l&rsquo;entreprise<\/strong><\/p>\n<p>\u00c9EM est une firme-conseil en d\u00e9veloppement durable qui offre aux organisations des secteurs priv\u00e9, public et \u00e0 but non lucratif une expertise dans les secteurs suivants : Environnement et Sant\u00e9-S\u00e9curit\u00e9 (ESS), \u00c9tudes d\u2019impact, Communaut\u00e9s et Strat\u00e9gie. Depuis plus de vingt ans, \u00c9EM aide ses clients \u00e0 incorporer le d\u00e9veloppement durable \u00e0 leurs pratiques d&rsquo;affaires en \u00e9tablissant un lien entre la planification strat\u00e9gique et la mise en \u0153uvre des solutions.<\/p>\n<p>\u00c9EM a pr\u00e9sentement un poste \u00e0 pourvoir pour un consultant en \u00e9tudes d\u2019impact social.<\/p>\n<p><strong>Responsabilit\u00e9s du poste :<\/strong><\/p>\n<p>Fournir des services-conseils en \u00e9tudes d\u2019impact social (\u00c9IS) et g\u00e9rer le processus d\u2019une \u00c9IS, comprenant principalement\u00a0:<\/p>\n<p>&#8211; G\u00e9rer des tiers contractants qui m\u00e8neront les \u00e9tudes appropri\u00e9es et les investigations pour le processus de l\u2019\u00c9IS ;<\/p>\n<p>&#8211; Assurer la conformit\u00e9 des \u00e9tudes et des plans de gestion avec les normes locales et internationales, incluant les normes canadiennes f\u00e9d\u00e9rales et provinciales et les normes de performance de la Soci\u00e9t\u00e9 financi\u00e8re internationale (SFI) ;<\/p>\n<p>&#8211; Effectuer des recherches de bases de donn\u00e9es existantes et des collectes de donn\u00e9es pour des projets sp\u00e9cifiques ;<\/p>\n<p>&#8211; Mener des activit\u00e9s de consultations communautaires dans le cadre de l\u2019\u00c9IS ;<\/p>\n<p>&#8211; Superviser la r\u00e9daction de l\u2019\u00e9tude d\u2019impact et prendre part \u00e0 sa r\u00e9daction en combinant les rapports des sp\u00e9cialistes, en r\u00e9sumant les divers impacts directs, indirects et cumulatifs des projets et en r\u00e9digeant des plans de gestion sociale\u00a0:<\/p>\n<p>&#8211; Participer aux prises de contact et communications avec le client, reli\u00e9es \u00e0 des projets sp\u00e9cifiques.<\/p>\n<p><strong>Exigences du poste : <\/strong><\/p>\n<p>Essentiel\u00a0: Bilingue \u2013 fran\u00e7ais et anglais (parl\u00e9 et \u00e9crit) \u2013 La personne devra \u00eatre en mesure d\u2019interagir et de r\u00e9diger des dans les deux langues.<\/p>\n<p>Essentiel\u00a0: Minimum de cinq (5) ann\u00e9es d&rsquo;exp\u00e9rience en \u00e9tudes d\u2019impact social et \u00e0 livrer des mandats \u00c9IS conforme aux normes de la SFI.<\/p>\n<p>Important\u00a0: Habilet\u00e9 \u00e0 traiter directement avec des clients, des membres de l\u2019\u00e9quipe et des agences de r\u00e8glementation.<\/p>\n<p>Important\u00a0: Comp\u00e9tences en gestion de projet (estimation et suivi des co\u00fbts, gestion de la relation avec le client, suivi des \u00e9ch\u00e9anciers, etc.).<\/p>\n<p>Important\u00a0: Capacit\u00e9 \u00e0 travailler en \u00e9quipe ainsi que de fa\u00e7on autonome avec un minimum de supervision.<\/p>\n<p>Atout\u00a0: Exp\u00e9rience sur des projets d\u2019\u00c9tudes d\u2019impact en Afrique de l\u2019ouest ou \u00e0 l\u2019international.<\/p>\n<p><strong>Mobilit\u00e9 : <\/strong>D\u00e9placements internationaux (maximum de 3 semaines \u00e0 la fois), selon les besoins de la client\u00e8le.<\/p>\n<p><strong>Information additionnelle : <\/strong>Le candidat choisit b\u00e9n\u00e9ficiera d&rsquo;une r\u00e9mun\u00e9ration concurrentielle et d&rsquo;un environnement de travail flexible o\u00f9 les contributions et les r\u00e9alisations visant l&rsquo;atteinte des objectifs de la firme sont r\u00e9compens\u00e9es.<\/p>\n<p><strong>Date de d\u00e9but :<\/strong> ao\u00fbt 2016.<\/p>\n<p><strong>Pour appliquer : <\/strong>Transmettre son curriculum vitae par courriel \u00e0 V\u00e9ronique Tousignant (<a href=\"mailto:veronique@eem.ca\">veronique@eem.ca<\/a>).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Description de l&rsquo;entreprise \u00c9EM est une firme-conseil en d\u00e9veloppement durable qui offre aux organisations des secteurs priv\u00e9, public et \u00e0 [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[80],"tags":[],"class_list":["post-2402","post","type-post","status-publish","format-standard","hentry","category-annonces"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Offre d&#039;emploi - Consultant en \u00e9valuation de l&#039;impact social - EEM - Gestion ESS<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.eem.ca\/fr\/2016\/07\/14\/consultant-en-matiere-d-evaluation-de-l-impact-social\/\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"webmaster@u7solutions.com\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.eem.ca\/fr\/2016\/07\/14\/consultant-en-matiere-d-evaluation-de-l-impact-social\/\",\"url\":\"https:\/\/www.eem.ca\/fr\/2016\/07\/14\/consultant-en-matiere-d-evaluation-de-l-impact-social\/\",\"name\":\"Offre d'emploi - Consultant en \u00e9valuation de l'impact social - EEM - Gestion ESS\",\"isPartOf\":{\"@id\":\"https:\/\/www.eem.ca\/#website\"},\"datePublished\":\"2016-07-14T12:31:53+00:00\",\"dateModified\":\"2016-11-30T21:51:49+00:00\",\"author\":{\"@id\":\"https:\/\/www.eem.ca\/#\/schema\/person\/b225f96e6d17fbee4df2c6340a4039b8\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.eem.ca\/fr\/2016\/07\/14\/consultant-en-matiere-d-evaluation-de-l-impact-social\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.eem.ca\/fr\/2016\/07\/14\/consultant-en-matiere-d-evaluation-de-l-impact-social\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.eem.ca\/fr\/2016\/07\/14\/consultant-en-matiere-d-evaluation-de-l-impact-social\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.eem.ca\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Offre d&#8217;emploi &#8211; Consultant en \u00e9valuation de l&rsquo;impact social\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.eem.ca\/#website\",\"url\":\"https:\/\/www.eem.ca\/\",\"name\":\"EEM - Gestion ESS\",\"description\":\"EEM Gestion ESS est une firme-conseil ind\u00e9pendante qui aide ses clients \u00e0 \u00e9valuer, g\u00e9rer et am\u00e9liorer leur performance en environnement, sant\u00e9 et s\u00e9curit\u00e9.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.eem.ca\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.eem.ca\/#\/schema\/person\/b225f96e6d17fbee4df2c6340a4039b8\",\"name\":\"webmaster@u7solutions.com\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Offre d'emploi - Consultant en \u00e9valuation de l'impact social - EEM - Gestion ESS","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.eem.ca\/fr\/2016\/07\/14\/consultant-en-matiere-d-evaluation-de-l-impact-social\/","twitter_misc":{"\u00c9crit par":"webmaster@u7solutions.com","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.eem.ca\/fr\/2016\/07\/14\/consultant-en-matiere-d-evaluation-de-l-impact-social\/","url":"https:\/\/www.eem.ca\/fr\/2016\/07\/14\/consultant-en-matiere-d-evaluation-de-l-impact-social\/","name":"Offre d'emploi - Consultant en \u00e9valuation de l'impact social - EEM - Gestion ESS","isPartOf":{"@id":"https:\/\/www.eem.ca\/#website"},"datePublished":"2016-07-14T12:31:53+00:00","dateModified":"2016-11-30T21:51:49+00:00","author":{"@id":"https:\/\/www.eem.ca\/#\/schema\/person\/b225f96e6d17fbee4df2c6340a4039b8"},"breadcrumb":{"@id":"https:\/\/www.eem.ca\/fr\/2016\/07\/14\/consultant-en-matiere-d-evaluation-de-l-impact-social\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.eem.ca\/fr\/2016\/07\/14\/consultant-en-matiere-d-evaluation-de-l-impact-social\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.eem.ca\/fr\/2016\/07\/14\/consultant-en-matiere-d-evaluation-de-l-impact-social\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.eem.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Offre d&#8217;emploi &#8211; Consultant en \u00e9valuation de l&rsquo;impact social"}]},{"@type":"WebSite","@id":"https:\/\/www.eem.ca\/#website","url":"https:\/\/www.eem.ca\/","name":"EEM - Gestion ESS","description":"EEM Gestion ESS est une firme-conseil ind\u00e9pendante qui aide ses clients \u00e0 \u00e9valuer, g\u00e9rer et am\u00e9liorer leur performance en environnement, sant\u00e9 et s\u00e9curit\u00e9.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.eem.ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.eem.ca\/#\/schema\/person\/b225f96e6d17fbee4df2c6340a4039b8","name":"webmaster@u7solutions.com"}]}},"_links":{"self":[{"href":"https:\/\/www.eem.ca\/fr\/wp-json\/wp\/v2\/posts\/2402","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eem.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.eem.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.eem.ca\/fr\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eem.ca\/fr\/wp-json\/wp\/v2\/comments?post=2402"}],"version-history":[{"count":0,"href":"https:\/\/www.eem.ca\/fr\/wp-json\/wp\/v2\/posts\/2402\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.eem.ca\/fr\/wp-json\/wp\/v2\/media?parent=2402"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.eem.ca\/fr\/wp-json\/wp\/v2\/categories?post=2402"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.eem.ca\/fr\/wp-json\/wp\/v2\/tags?post=2402"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}